{"id":9967,"date":"2026-05-25T10:40:00","date_gmt":"2026-05-25T10:40:00","guid":{"rendered":"https:\/\/anastacio.com\/?p=9967"},"modified":"2026-08-27T14:17:35","modified_gmt":"2026-08-27T14:17:35","slug":"nova-parceria-quimica-anastacio-e-clariant","status":"publish","type":"post","link":"https:\/\/anastacio.com\/es\/nova-parceria-quimica-anastacio-e-clariant\/","title":{"rendered":"Nueva alianza entre Qu\u00edmica Anastacio y Clariant"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Qu\u00edmica Anastacio, una de las mayores distribuidoras de Am\u00e9rica Latina, ofrece un portafolio completo de productos e ingredientes, junto con soluciones y servicios inteligentes que apoyan a clientes y proveedores en el crecimiento de sus negocios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00c9 com grande satisfa\u00e7\u00e3o que anunciamos uma nova parceria de distribui\u00e7\u00e3o com a Clariant, destinada \u00e0 unidade de neg\u00f3cios Farmac\u00eauticos.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Clariant es una de las principales compa\u00f1\u00edas globales de especialidades qu\u00edmicas, reconocida por sus soluciones orientadas a generar valor para diferentes industrias. Su portafolio est\u00e1 desarrollado para atender necesidades espec\u00edficas con un alto nivel de precisi\u00f3n, mientras que sus iniciativas de investigaci\u00f3n y desarrollo est\u00e1n enfocadas en las principales tendencias globales, como la eficiencia energ\u00e9tica, el uso de materias primas renovables, la movilidad de bajas emisiones y la preservaci\u00f3n de los recursos naturales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con presencia global, la compa\u00f1\u00eda est\u00e1 estructurada en las unidades de negocios Care Chemicals, Adsorbents &amp; Additives y Catalysts, y cuenta con m\u00e1s de 10 mil colaboradores alrededor del mundo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>A partir de ahora, Qu\u00edmica Anastacio pasa a actuar como distribuidora, en Brasil, de la l\u00ednea de excipientes de Clariant, incluyendo:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph translation-block\">\u2022    Polyglykol \u2013 Polietilenglicoles (PEGs o Macrogol) utilizados como excipientes. Excipientes: pesos moleculares de 200 a 35.000.<br>\n\u2022    VitiPure\u2122 \u2013 Solubilizantes, solventes e emulsificantes para diversas aplica\u00e7\u00f5es farmac\u00eauticas <br>\n\u2022    VitiPure\u2122 LEX \u2013 Solubilizantes, solventes e emulsificantes com controle microbiol\u00f3gico e de endotoxina por lote, indicados para aplica\u00e7\u00f5es de alto risco <br>\n\u2022    VitiPure\u2122 Superior \u2013 Solubilizantes, solventes e emulsificantes altamente purificados para aplica\u00e7\u00f5es parenterais e IFAs sens\u00edveis <br>\n\u2022    Motusflex \u2013 Modificadores reol\u00f3gicos de alta performance para aplica\u00e7\u00f5es t\u00f3picas, como g\u00e9is, cremes e creme-gel<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta alianza refuerza el compromiso de Qu\u00edmica Anastacio de ampliar continuamente su portafolio de soluciones para el mercado farmac\u00e9utico, conectando innovaci\u00f3n, tecnolog\u00eda y soporte t\u00e9cnico especializado con las necesidades de la industria.<\/p>","protected":false},"excerpt":{"rendered":"<p>A Qu\u00edmica Anastacio, uma das maiores distribuidoras da Am\u00e9rica Latina, oferece um portf\u00f3lio completo de produtos e ingredientes, aliado a solu\u00e7\u00f5es e servi\u00e7os inteligentes que apoiam clientes e fornecedores no crescimento de seus neg\u00f3cios. \u00c9 com grande satisfa\u00e7\u00e3o que anunciamos uma nova parceria de distribui\u00e7\u00e3o com a Clariant, destinada \u00e0 unidade de neg\u00f3cios Farmac\u00eauticos. A [&hellip;]<\/p>","protected":false},"author":7,"featured_media":9968,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[53],"tags":[],"class_list":["post-9967","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/anastacio.com\/es\/wp-json\/wp\/v2\/posts\/9967","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/anastacio.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/anastacio.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/anastacio.com\/es\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/anastacio.com\/es\/wp-json\/wp\/v2\/comments?post=9967"}],"version-history":[{"count":0,"href":"https:\/\/anastacio.com\/es\/wp-json\/wp\/v2\/posts\/9967\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/anastacio.com\/es\/wp-json\/wp\/v2\/media\/9968"}],"wp:attachment":[{"href":"https:\/\/anastacio.com\/es\/wp-json\/wp\/v2\/media?parent=9967"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/anastacio.com\/es\/wp-json\/wp\/v2\/categories?post=9967"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/anastacio.com\/es\/wp-json\/wp\/v2\/tags?post=9967"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}